{"id":8416,"date":"2016-01-04T10:04:12","date_gmt":"2016-01-04T13:04:12","guid":{"rendered":"http:\/\/www.impacta.com.br\/blog\/?p=8416"},"modified":"2016-01-04T10:04:12","modified_gmt":"2016-01-04T13:04:12","slug":"pantone-divulga-cor-de-2016-e-sao-duas","status":"publish","type":"post","link":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/","title":{"rendered":"Pantone divulga cor de 2016. E s\u00e3o duas!"},"content":{"rendered":"<p style=\"text-align: justify;\">A <strong>Pantone<\/strong>, reconhecida como autoridade mundial em escala de cores, divulga desde 2000 a cor que ser\u00e1 tend\u00eancia durante o ano, assim como mostramos a <a title=\"Pantone revela a cor do ano para 2015: Marsala\" href=\"https:\/\/www.impacta.com.br\/blog\/2014\/12\/05\/pantone-revela-cor-ano-para-2015-marsala\/\" target=\"_blank\" rel=\"noopener noreferrer\">marsala de 2015<\/a> e o<a title=\"A Pantone j\u00e1 escolheu sua cor para o Ano Novo: Roxo\" href=\"https:\/\/www.impacta.com.br\/blog\/2013\/12\/19\/a-pantone-ja-escolheu-sua-cor-para-o-ano-novo-roxo\/\" target=\"_blank\" rel=\"noopener noreferrer\"> roxo de 2014<\/a>. A novidade para cor de 2016 \u00e9 que a empresa escolheu n\u00e3o uma, mas duas cores que ditar\u00e3o a a ind\u00fastria gr\u00e1fica, os profissionais e companhias do universo das artes em todo o mundo.<\/p>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 12pt;\">A cor de 2016 na verdade s\u00e3o duas<\/span><\/h2>\n<p style=\"text-align: justify;\">O <strong>Rose Quartz<\/strong> (na escala &#8211; Pantone 13-1520) e o <strong>Serenity<\/strong> (Pantone 15-3919) s\u00e3o as cores de 2016. &#8220;Juntas, demonstram um equil\u00edbrio inerente entre um rosa quente acolhedor e um azul mais suave, refletindo uma cone\u00e7\u00e3o e bem estar bem como uma senso de ordem e paz&#8221;, afirma a Pantone.<\/p>\n<p style=\"text-align: center;\"><video controls=\"controls\" width=\"600\" height=\"300\"><source src=\"https:\/\/xritemedia-a.akamaihd.net\/40bWwweTpxAJbkHGVXIHtxUKbpvUsPRK\/DOcJ-FxaFrRg4gtDEwOnI5OjBzMTsHuR\" \/><\/video><\/p>\n<p style=\"text-align: justify;\">O pink delicado\u00a0 do Rose Quartz\u00a0\u00e9 apontado como a principal cor para o ver\u00e3o 2016, portanto o tom dever\u00e1 dominar os guarda-roupas e vitrines muito em breve. Mas a mescla das duas cores \u00e9 que representa o ano, desafiando as percep\u00e7\u00f5es tradicionais de associa\u00e7\u00e3o de cores, como diz a empresa.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2015\/12\/Pantone_Color_of_the_Year_2016_shop_Pantone_Plastic_Chips.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8418 size-full\" title=\"Pela primeira vez a Pantone escolheu duas cores para a cor de 2016\" src=\"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2015\/12\/Pantone_Color_of_the_Year_2016_shop_Pantone_Plastic_Chips.jpg\" alt=\"Pela primeira vez a Pantone escolheu duas cores para a cor de 2016\" width=\"233\" height=\"330\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong>Top 10 das cores do Ver\u00e3o 2016 Pantone<\/strong><\/span><\/h2>\n<p style=\"text-align: justify;\">Al\u00e9m do Rose Quartz e do azul Serenity, tamb\u00e9m foram anunciadas outras oito cores do novo top 10 para o ver\u00e3o 2016 da escala Pantone. O detalhe e a grande presen\u00e7a de tons suaves que, segundo Leatrice Eiseman, diretora executiva do Instituto de Cor da Pantone, se explicam pela necessidade de cores aconchegantes e mais leves.<\/p>\n<p style=\"text-align: justify;\">As cores s\u00e3o: <strong>Peach Echo, Snorkel Blue, Limpet Shell, Lilac Gray, Buttercup, Fiesta, Iced Coffee e Green Flash<\/strong>. Destes, os tr\u00eas \u00faltimos s\u00e3o mais fortes e permitem combina\u00e7\u00f5es diferentes. Veja todas as cores <a title=\"Top 10 das cores para o ver\u00e3o 2016\" href=\"https:\/\/www.pantone.com\/pages\/fcr\/?season=spring&amp;year=2016\" target=\"_blank\" rel=\"noopener noreferrer\">aqui<\/a>.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2015\/12\/FCR-SPRING2016-Home-Banner-Img.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8417\" title=\"Escala apresenta o top 10 das cores tend\u00eancias de 2016\" src=\"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2015\/12\/FCR-SPRING2016-Home-Banner-Img.jpg\" alt=\"Escala apresenta o top 10 das cores tend\u00eancias de 2016\" width=\"450\" height=\"359\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">E a\u00ed, o que achou das cores escolhidas? Tenho certeza que neste ano voc\u00ea as ver\u00e1 muito por a\u00ed. Deixe seu coment\u00e1rio e nos conte o que achou.<\/p>\n<p style=\"text-align: justify;\">O design e arte s\u00e3o \u00e1reas muito influenciadas pelas cores e suas tend\u00eancias do ano. Que tal conhecer os cursos de <a title=\"Cursos de arte e design da Impacta\" href=\"https:\/\/www.impacta.com.br\/escola\/Art-e-Design\" target=\"_blank\" rel=\"noopener noreferrer\">design da Impacta<\/a> e se preparar para um 2016 ainda melhor? Aproveite.<\/p>\n<div class=\"sharing-default-minimal post-bottom\"><div class=\"nectar-social default\" data-position=\"\" data-rm-love=\"0\" data-color-override=\"override\"><div class=\"nectar-social-inner\"><a href=\"#\" class=\"nectar-love\" id=\"nectar-love-8416\" title=\"Love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">Love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a><a class='facebook-share nectar-sharing' href='#' title='Share this'> <i class='fa fa-facebook'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='twitter-share nectar-sharing' href='#' title='Share this'> <i class='fa icon-salient-x-twitter'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='linkedin-share nectar-sharing' href='#' title='Share this'> <i class='fa fa-linkedin'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='pinterest-share nectar-sharing' href='#' title='Pin this'> <i class='fa fa-pinterest'><\/i> <span class='social-text'>Pin<\/span> <\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Pantone, reconhecida como autoridade mundial em escala de cores, divulga desde 2000 a cor que ser\u00e1 tend\u00eancia durante o ano, assim como mostramos a marsala de 2015 e o roxo de 2014. A novidade para cor de 2016 \u00e9 que a empresa escolheu n\u00e3o uma, mas duas cores que ditar\u00e3o a a ind\u00fastria gr\u00e1fica, [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":17510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[180,181],"class_list":["post-8416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-design","tag-cor-do-ano","tag-pantone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Pantone divulga cor de 2016. E s\u00e3o duas!<\/title>\r\n<meta name=\"description\" content=\"A Pantone j\u00e1 escolheu e divulgou a cor de 2016. A grande surpresa \u00e9 que esse ano n\u00e3o s\u00f3 uma, mas duas cores \u00e9 que ditaram a moda, design e a arte. Conhe\u00e7a.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/\" \/>\r\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Pantone divulga cor de 2016. E s\u00e3o duas!\" \/>\r\n<meta property=\"og:description\" content=\"A Pantone j\u00e1 escolheu e divulgou a cor de 2016. A grande surpresa \u00e9 que esse ano n\u00e3o s\u00f3 uma, mas duas cores \u00e9 que ditaram a moda, design e a arte. Conhe\u00e7a.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Blog Impacta - Dicas e Not\u00edcias sobre Carreira\" \/>\r\n<meta property=\"article:published_time\" content=\"2016-01-04T13:04:12+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2020\/04\/header_pantone.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"850\" \/>\r\n\t<meta property=\"og:image:height\" content=\"284\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Bruno Saes\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Saes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/\",\"url\":\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/\",\"name\":\"Pantone divulga cor de 2016. E s\u00e3o duas!\",\"isPartOf\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2020\/04\/header_pantone.jpg\",\"datePublished\":\"2016-01-04T13:04:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/a11cbe0acd0fe8d8904443861a5f215c\"},\"description\":\"A Pantone j\u00e1 escolheu e divulgou a cor de 2016. A grande surpresa \u00e9 que esse ano n\u00e3o s\u00f3 uma, mas duas cores \u00e9 que ditaram a moda, design e a arte. Conhe\u00e7a.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#primaryimage\",\"url\":\"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2020\/04\/header_pantone.jpg\",\"contentUrl\":\"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2020\/04\/header_pantone.jpg\",\"width\":850,\"height\":284},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.impacta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pantone divulga cor de 2016. E s\u00e3o duas!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#website\",\"url\":\"https:\/\/www.impacta.com.br\/blog\/\",\"name\":\"Blog Impacta - Dicas e Not\u00edcias sobre Carreira\",\"description\":\"Dicas, Not\u00edcias e Conte\u00fados sobre Carreira, Tecnologia, Design, Gest\u00e3o e Marketing. Conhe\u00e7a e Acompanhe o Blog Impacta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.impacta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/a11cbe0acd0fe8d8904443861a5f215c\",\"name\":\"Bruno Saes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a4f7799d79cbb7873b2b27e86e09f786?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a4f7799d79cbb7873b2b27e86e09f786?s=96&d=mm&r=g\",\"caption\":\"Bruno Saes\"},\"url\":\"https:\/\/www.impacta.com.br\/blog\/author\/bruno-saes\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pantone divulga cor de 2016. E s\u00e3o duas!","description":"A Pantone j\u00e1 escolheu e divulgou a cor de 2016. A grande surpresa \u00e9 que esse ano n\u00e3o s\u00f3 uma, mas duas cores \u00e9 que ditaram a moda, design e a arte. Conhe\u00e7a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/","og_locale":"pt_BR","og_type":"article","og_title":"Pantone divulga cor de 2016. E s\u00e3o duas!","og_description":"A Pantone j\u00e1 escolheu e divulgou a cor de 2016. A grande surpresa \u00e9 que esse ano n\u00e3o s\u00f3 uma, mas duas cores \u00e9 que ditaram a moda, design e a arte. Conhe\u00e7a.","og_url":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/","og_site_name":"Blog Impacta - Dicas e Not\u00edcias sobre Carreira","article_published_time":"2016-01-04T13:04:12+00:00","og_image":[{"width":850,"height":284,"url":"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2020\/04\/header_pantone.jpg","type":"image\/jpeg"}],"author":"Bruno Saes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bruno Saes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/","url":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/","name":"Pantone divulga cor de 2016. E s\u00e3o duas!","isPartOf":{"@id":"https:\/\/www.impacta.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#primaryimage"},"image":{"@id":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2020\/04\/header_pantone.jpg","datePublished":"2016-01-04T13:04:12+00:00","author":{"@id":"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/a11cbe0acd0fe8d8904443861a5f215c"},"description":"A Pantone j\u00e1 escolheu e divulgou a cor de 2016. A grande surpresa \u00e9 que esse ano n\u00e3o s\u00f3 uma, mas duas cores \u00e9 que ditaram a moda, design e a arte. Conhe\u00e7a.","breadcrumb":{"@id":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#primaryimage","url":"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2020\/04\/header_pantone.jpg","contentUrl":"https:\/\/www.impacta.com.br\/blog\/wp-content\/uploads\/2020\/04\/header_pantone.jpg","width":850,"height":284},{"@type":"BreadcrumbList","@id":"https:\/\/www.impacta.com.br\/blog\/pantone-divulga-cor-de-2016-e-sao-duas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.impacta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pantone divulga cor de 2016. E s\u00e3o duas!"}]},{"@type":"WebSite","@id":"https:\/\/www.impacta.com.br\/blog\/#website","url":"https:\/\/www.impacta.com.br\/blog\/","name":"Blog Impacta - Dicas e Not\u00edcias sobre Carreira","description":"Dicas, Not\u00edcias e Conte\u00fados sobre Carreira, Tecnologia, Design, Gest\u00e3o e Marketing. Conhe\u00e7a e Acompanhe o Blog Impacta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.impacta.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/a11cbe0acd0fe8d8904443861a5f215c","name":"Bruno Saes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a4f7799d79cbb7873b2b27e86e09f786?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a4f7799d79cbb7873b2b27e86e09f786?s=96&d=mm&r=g","caption":"Bruno Saes"},"url":"https:\/\/www.impacta.com.br\/blog\/author\/bruno-saes\/"}]}},"acf":{"post_description":null,"capa_mobile":null},"_links":{"self":[{"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/posts\/8416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8416"}],"version-history":[{"count":0,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/posts\/8416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/media\/17510"}],"wp:attachment":[{"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}