{"id":4767,"date":"2014-12-05T16:54:26","date_gmt":"2014-12-05T19:54:26","guid":{"rendered":"http:\/\/blogimpacta.com.br\/?p=4767"},"modified":"2014-12-05T16:54:26","modified_gmt":"2014-12-05T19:54:26","slug":"pantone-revela-cor-ano-para-2015-marsala","status":"publish","type":"post","link":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/","title":{"rendered":"Pantone revela a cor do ano para 2015: Marsala"},"content":{"rendered":"<p style=\"text-align: justify;\">Como j\u00e1 virou tradi\u00e7\u00e3o, a <strong>Pantone<\/strong> revela qual a cor escolhida como tend\u00eancia para 2015. A divulga\u00e7\u00e3o pode at\u00e9 soar de maneira estranha para quem n\u00e3o \u00e9 do ramo de design, por\u00e9m, \u00e9 muito importante, visto que reflete em toda a ind\u00fastria gr\u00e1fica, servindo como influ\u00eancia aos profissionais e empresas do universo das artes em todo o mundo.<\/p>\n<p style=\"text-align: justify;\">A empresa, reconhecida como autoridade mundial em escala de cores, apontou para o pr\u00f3ximo ano um tom marrom-avermelhado, chamado de <strong>Marsala<\/strong>, o mesmo nome de um tipo de vinho italiano.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4769\" title=\"Cor com nome de vinho italiano \u00e9 a tend\u00eancia da Pantone para 2015\" src=\"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg\" alt=\"Cor com nome de vinho italiano \u00e9 a tend\u00eancia da Pantone para 2015\" width=\"440\" height=\"294\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">A escolha da Pantone para 2015 chamou bastante aten\u00e7\u00e3o por dois motivos. O primeiro,\u00a0que\u00a0causa um verdadeiro choque no p\u00fablico, ocorreu muito provavelmente devido ao tamanho da diferen\u00e7a entre a Marsala e as cores escolhidas nos anos anteriores. O novo tom tem um aspecto muito mais s\u00e9rio e fechado, diferenciando-se das escolhas vivas e alegres de 2012, com o <strong>Tangerine Tango<\/strong>, 2013, com <strong>Emerald<\/strong>, e 2014, com <strong>Radiant Orchid<\/strong> (escolha que tamb\u00e9m foi divulgada aqui no <a title=\"Cor da Pantone de 2014 foi o roxo\" href=\"https:\/\/www.impacta.com.br\/blog2013\/12\/19\/a-pantone-ja-escolheu-sua-cor-para-o-ano-novo-roxo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Blog Impacta<\/a>).<\/p>\n<h1 style=\"text-align: center;\"><span style=\"font-size: 10pt;\">Divulga\u00e7\u00e3o da Pantone gera piadas na web<\/span><\/h1>\n<p style=\"text-align: justify;\">O segundo motivo que causou muita repercuss\u00e3o, principalmente nas redes sociais, \u00e9 referente ao nome da cor. Acontece que, al\u00e9m de ser um nome de vinho, Marsala \u00e9 nomenclatura de um molho da rede de comida italiana <strong>Olive Garden<\/strong>, fato que gerou muitas piadas na internet.<\/p>\n<p style=\"text-align: justify;\">Claramente a escolha da Pantone n\u00e3o teve nenhuma liga\u00e7\u00e3o com a rede de alimenta\u00e7\u00e3o. Em <a title=\"Em release de apresenta\u00e7\u00e3o, Pantone justifica a escolha\" href=\"https:\/\/www.prnewswire.com\/news-releases\/pantone-reveals-color-of-the-year-for-2015-pantone-18-1438-marsala-300004731.html\" target=\"_blank\" rel=\"noopener noreferrer\">release<\/a> para apresentar a cor, a empresa explica o conceito sobre o tom de 2015: \u201cAssim como o fortificado vinho que d\u00e1 o nome \u00e0 Marsala, esse tom saboroso engloba a riqueza satisfat\u00f3ria de uma farta refei\u00e7\u00e3o, enquanto as suas ra\u00edzes marrom-avermelhadas emanam uma sofisticada e natural sensa\u00e7\u00e3o terrosa\u201d.<\/p>\n<p style=\"text-align: justify;\">Voc\u00ea podia at\u00e9 n\u00e3o conhecer essa cor, por\u00e9m, agora ter\u00e1 a certeza que em 2015 ir\u00e1 encontr\u00e1-la bastante, seja nas passarelas de desfiles de moda, em sites, na decora\u00e7\u00e3o de ambientes e at\u00e9 mesmo nos itens de maquiagem.<\/p>\n<div class=\"sharing-default-minimal post-bottom\"><div class=\"nectar-social default\" data-position=\"\" data-rm-love=\"0\" data-color-override=\"override\"><div class=\"nectar-social-inner\"><a href=\"#\" class=\"nectar-love\" id=\"nectar-love-4767\" title=\"Love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">Love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">0<\/span><\/span><\/a><a class='facebook-share nectar-sharing' href='#' title='Share this'> <i class='fa fa-facebook'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='twitter-share nectar-sharing' href='#' title='Share this'> <i class='fa icon-salient-x-twitter'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='linkedin-share nectar-sharing' href='#' title='Share this'> <i class='fa fa-linkedin'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='pinterest-share nectar-sharing' href='#' title='Pin this'> <i class='fa fa-pinterest'><\/i> <span class='social-text'>Pin<\/span> <\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Como j\u00e1 virou tradi\u00e7\u00e3o, a Pantone revela qual a cor escolhida como tend\u00eancia para 2015. A divulga\u00e7\u00e3o pode at\u00e9 soar de maneira estranha para quem n\u00e3o \u00e9 do ramo de design, por\u00e9m, \u00e9 muito importante, visto que reflete em toda a ind\u00fastria gr\u00e1fica, servindo como influ\u00eancia aos profissionais e empresas do universo das artes em todo o mundo.<br \/>\nA empresa, reconhecida como autoridade mundial em escala de cores, apontou para o pr\u00f3ximo ano um tom marrom-avermelhado, chamado de Marsala, o mesmo nome de um tipo de vinho italiano.<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[180,181],"class_list":["post-4767","post","type-post","status-publish","format-standard","hentry","category-arte-design","tag-cor-do-ano","tag-pantone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Pantone revela a cor do ano para 2015: Marsala<\/title>\r\n<meta name=\"description\" content=\"Pantone apontou um tom marrom-avermelhado, inspirado em um vinho italiano e chamado de Marsala, como a cor tend\u00eancia para o ano de 2015.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/\" \/>\r\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Pantone revela a cor do ano para 2015: Marsala\" \/>\r\n<meta property=\"og:description\" content=\"Pantone apontou um tom marrom-avermelhado, inspirado em um vinho italiano e chamado de Marsala, como a cor tend\u00eancia para o ano de 2015.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Blog Impacta - Dicas e Not\u00edcias sobre Carreira\" \/>\r\n<meta property=\"article:published_time\" content=\"2014-12-05T19:54:26+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg\" \/>\r\n<meta name=\"author\" content=\"Bruno Saes\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Saes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/\",\"url\":\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/\",\"name\":\"Pantone revela a cor do ano para 2015: Marsala\",\"isPartOf\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg\",\"datePublished\":\"2014-12-05T19:54:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/a11cbe0acd0fe8d8904443861a5f215c\"},\"description\":\"Pantone apontou um tom marrom-avermelhado, inspirado em um vinho italiano e chamado de Marsala, como a cor tend\u00eancia para o ano de 2015.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#primaryimage\",\"url\":\"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg\",\"contentUrl\":\"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.impacta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pantone revela a cor do ano para 2015: Marsala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#website\",\"url\":\"https:\/\/www.impacta.com.br\/blog\/\",\"name\":\"Blog Impacta - Dicas e Not\u00edcias sobre Carreira\",\"description\":\"Dicas, Not\u00edcias e Conte\u00fados sobre Carreira, Tecnologia, Design, Gest\u00e3o e Marketing. Conhe\u00e7a e Acompanhe o Blog Impacta\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.impacta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/a11cbe0acd0fe8d8904443861a5f215c\",\"name\":\"Bruno Saes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a4f7799d79cbb7873b2b27e86e09f786?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a4f7799d79cbb7873b2b27e86e09f786?s=96&d=mm&r=g\",\"caption\":\"Bruno Saes\"},\"url\":\"https:\/\/www.impacta.com.br\/blog\/author\/bruno-saes\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pantone revela a cor do ano para 2015: Marsala","description":"Pantone apontou um tom marrom-avermelhado, inspirado em um vinho italiano e chamado de Marsala, como a cor tend\u00eancia para o ano de 2015.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/","og_locale":"pt_BR","og_type":"article","og_title":"Pantone revela a cor do ano para 2015: Marsala","og_description":"Pantone apontou um tom marrom-avermelhado, inspirado em um vinho italiano e chamado de Marsala, como a cor tend\u00eancia para o ano de 2015.","og_url":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/","og_site_name":"Blog Impacta - Dicas e Not\u00edcias sobre Carreira","article_published_time":"2014-12-05T19:54:26+00:00","og_image":[{"url":"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg","type":"","width":"","height":""}],"author":"Bruno Saes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bruno Saes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/","url":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/","name":"Pantone revela a cor do ano para 2015: Marsala","isPartOf":{"@id":"https:\/\/www.impacta.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#primaryimage"},"image":{"@id":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#primaryimage"},"thumbnailUrl":"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg","datePublished":"2014-12-05T19:54:26+00:00","author":{"@id":"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/a11cbe0acd0fe8d8904443861a5f215c"},"description":"Pantone apontou um tom marrom-avermelhado, inspirado em um vinho italiano e chamado de Marsala, como a cor tend\u00eancia para o ano de 2015.","breadcrumb":{"@id":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#primaryimage","url":"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg","contentUrl":"https:\/\/blogimpacta.com.br\/wp-content\/uploads\/2014\/12\/marsala-6.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.impacta.com.br\/blog\/pantone-revela-cor-ano-para-2015-marsala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.impacta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pantone revela a cor do ano para 2015: Marsala"}]},{"@type":"WebSite","@id":"https:\/\/www.impacta.com.br\/blog\/#website","url":"https:\/\/www.impacta.com.br\/blog\/","name":"Blog Impacta - Dicas e Not\u00edcias sobre Carreira","description":"Dicas, Not\u00edcias e Conte\u00fados sobre Carreira, Tecnologia, Design, Gest\u00e3o e Marketing. Conhe\u00e7a e Acompanhe o Blog Impacta","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.impacta.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/a11cbe0acd0fe8d8904443861a5f215c","name":"Bruno Saes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.impacta.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a4f7799d79cbb7873b2b27e86e09f786?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a4f7799d79cbb7873b2b27e86e09f786?s=96&d=mm&r=g","caption":"Bruno Saes"},"url":"https:\/\/www.impacta.com.br\/blog\/author\/bruno-saes\/"}]}},"acf":{"post_description":null,"capa_mobile":null},"_links":{"self":[{"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/posts\/4767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4767"}],"version-history":[{"count":0,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/posts\/4767\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.impacta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}